

{"id":501,"date":"2021-02-14T18:40:26","date_gmt":"2021-02-14T18:40:26","guid":{"rendered":"https:\/\/lescriva.com\/?post_type=product&#038;p=501"},"modified":"2021-03-15T10:21:32","modified_gmt":"2021-03-15T10:21:32","slug":"guixos-de-colors","status":"publish","type":"product","link":"https:\/\/lescriva.com\/es\/producte\/guixos-de-colors\/","title":{"rendered":"Guixos de colors"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>Guixos rodons de sulfat de calci (no contenen case\u00efna). Cont\u00e9 2 guixos de cada color: groc, blau, taronja, vermell, verd.<\/p>\n<div><a href=\"https:\/\/lescriva.com\/es\/producte\/guixos-de-colors\/\" class=\"exp-read-more exp-read-more-underlined\">Read More<\/a><\/div>\n","protected":false},"featured_media":500,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[23],"product_tag":[62,60,88,68,63,56,89,91,90],"class_list":{"0":"post-501","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-papereria","7":"product_tag-colores","8":"product_tag-colors","9":"product_tag-guixos","10":"product_tag-manualitats","11":"product_tag-material-escolar","12":"product_tag-milan1918","13":"product_tag-pissarra","14":"product_tag-pizarra","15":"product_tag-tizas","17":"first","18":"instock","19":"taxable","20":"shipping-taxable","21":"purchasable","22":"product-type-simple"},"_links":{"self":[{"href":"https:\/\/lescriva.com\/es\/wp-json\/wp\/v2\/product\/501","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lescriva.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/lescriva.com\/es\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/lescriva.com\/es\/wp-json\/wp\/v2\/comments?post=501"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lescriva.com\/es\/wp-json\/wp\/v2\/media\/500"}],"wp:attachment":[{"href":"https:\/\/lescriva.com\/es\/wp-json\/wp\/v2\/media?parent=501"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/lescriva.com\/es\/wp-json\/wp\/v2\/product_brand?post=501"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/lescriva.com\/es\/wp-json\/wp\/v2\/product_cat?post=501"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/lescriva.com\/es\/wp-json\/wp\/v2\/product_tag?post=501"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}